{"id":45,"date":"2013-06-03T21:37:17","date_gmt":"2013-06-04T00:37:17","guid":{"rendered":"http:\/\/radames.manosso.nom.br\/linguagem\/?p=45"},"modified":"2020-11-19T14:28:12","modified_gmt":"2020-11-19T17:28:12","slug":"retorica-da-oratoria","status":"publish","type":"post","link":"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-oratoria\/","title":{"rendered":"Ret\u00f3rica da orat\u00f3ria"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Orat\u00f3ria \u00e9 a arte do discurso p\u00fablico em tempo real. No discurso orat\u00f3rio \u00e9 marcante a caracter\u00edstica perform\u00e1tica. N\u00e3o basta que ele tenha sido bem planejado, bem redigido, tem de ser bem emitido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O orador tem de zelar pela sua apar\u00eancia, pois o ouvinte pode fazer uma transfer\u00eancia ic\u00f4nica a partir da apar\u00eancia do orador para o conte\u00fado do discurso. A imagem do orador deve despertar na plateia a impress\u00e3o por ele premeditada. Para isso, o orador precisa conhecer as expectativas de sua plateia e se beneficiar disso. Esta regra, de moralidade duvidosa, faz a orat\u00f3ria, em certos casos, parecer uma arte de dissimula\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?resize=500%2C333&#038;ssl=1\" alt=\"Ret\u00f3rica\" class=\"wp-image-3283\" title=\"Ret\u00f3rica\" srcset=\"https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?w=500&amp;ssl=1 500w, https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\">Defeitos a evitar<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Titubeio: prejudica a imagem do orador. O receptor associa o titubeio \u00e0 inseguran\u00e7a de personalidade.<\/li><li>A velocidade inadequada de entoa\u00e7\u00e3o, muito lenta ou muito r\u00e1pida, influi na comunicabilidade. A velocidade ideal \u00e9 conseguida com a pr\u00e1tica.<\/li><li>Pronunciar express\u00f5es cuja \u00fanica fun\u00e7\u00e3o \u00e9 preencher a lacuna de um titubeio. Exemplos: &#8216;n\u00e9&#8217;, &#8216;hum&#8217;, &#8216;ahn&#8217;. Por vezes, repetem-se as \u00faltimas palavras que antecederam o titubeio.<\/li><li>M\u00e1 dic\u00e7\u00e3o: \u00e9 a pron\u00fancia inadequada dos fonemas, que n\u00e3o resultam n\u00edtidos ao ouvido do receptor.<\/li><li>Pausas de pron\u00fancia que n\u00e3o coincidem com pausas sint\u00e1ticas. Caso not\u00e1vel \u00e9 a pausa provocada por falta de ar.<\/li><li>Problemas de qualidade da voz: fanhosa, muito aguda ou muito grave.<\/li><li>Volume muito fraco ou muito intenso da voz.<\/li><li>Uso de variantes de pros\u00f3dia conotadas pejorativamente pela plat\u00e9ia.<\/li><li>Predom\u00ednio dos recursos de entoa\u00e7\u00e3o e gesticula\u00e7\u00e3o. \u00c9 o c\u00f3digo ling\u00fc\u00edstico que deve predominar.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Ret\u00f3ricas espec\u00edficas<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-influencia\/\">Ret\u00f3rica da persuas\u00e3o<\/a><\/li><li><a href=\"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-literatura\/\">Ret\u00f3rica da Literatura<\/a><\/li><li><a href=\"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-monografia\/\">Ret\u00f3rica da monografia<\/a><\/li><li><a href=\"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-oratoria\/\">Ret\u00f3rica da orat\u00f3ria<\/a><\/li><li><a href=\"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-do-jornalismo\/\">Ret\u00f3rica do jornalismo<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Orat\u00f3ria \u00e9 a arte do discurso p\u00fablico em tempo real. No discurso orat\u00f3rio \u00e9 marcante a caracter\u00edstica perform\u00e1tica. N\u00e3o basta que ele tenha sido bem planejado, bem redigido, tem de ser bem emitido. O orador tem de zelar pela sua apar\u00eancia, pois o ouvinte pode fazer uma transfer\u00eancia ic\u00f4nica a partir da apar\u00eancia do orador &hellip; <a href=\"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-oratoria\/\" class=\"more-link\">Continue lendo <span class=\"screen-reader-text\">Ret\u00f3rica da orat\u00f3ria<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[14,24,5],"class_list":["post-45","post","type-post","status-publish","format-standard","hentry","category-retoricas","tag-discurso","tag-oratoria","tag-retorica-2"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p74YWN-J","jetpack-related-posts":[{"id":29,"url":"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/para-comecar\/o-escopo-da-retorica\/","url_meta":{"origin":45,"position":0},"title":"O escopo da Ret\u00f3rica","author":"Radam\u00e9s","date":false,"format":false,"excerpt":"A Ret\u00f3rica ocupa-se dos meios formais que tornam a comunica\u00e7\u00e3o espec\u00edfica ou eficaz, tais como regras de uso ou supress\u00e3o e formas construtivas, al\u00e9m de categorias relacionadas. \u00c9 um conhecimento sobre essas categorias, suas caracter\u00edsticas, funcionalidade, efic\u00e1cia e excel\u00eancia. Para que a comunica\u00e7\u00e3o seja eficaz sup\u00f5e-se que vise a objetivos\u2026","rel":"","context":"Em &quot;Para come\u00e7ar&quot;","block_context":{"text":"Para come\u00e7ar","link":"https:\/\/radames.manosso.nom.br\/linguagem\/category\/retorica\/para-comecar\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":41,"url":"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-literatura\/","url_meta":{"origin":45,"position":1},"title":"Ret\u00f3rica da Literatura","author":"Radam\u00e9s","date":false,"format":false,"excerpt":"A Ret\u00f3rica\u00a0 liter\u00e1ria \u00e9 a mais dif\u00edcil de delimitar. Em literatura, mimetiza-se o formal e o informal, o espont\u00e2neo e o elaborado, o orat\u00f3rio, o jornal\u00edstico, a discuss\u00e3o, o col\u00f3quio e o debate. Assim, a Ret\u00f3rica da literatura nestes casos ser\u00e1 a Ret\u00f3rica do jornal\u00edstico, do col\u00f3quio, do debate, etc.\u2026","rel":"","context":"Em &quot;Ret\u00f3ricas&quot;","block_context":{"text":"Ret\u00f3ricas","link":"https:\/\/radames.manosso.nom.br\/linguagem\/category\/retorica\/retoricas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":31,"url":"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/para-comecar\/a-renovacao-da-retorica\/","url_meta":{"origin":45,"position":2},"title":"A renova\u00e7\u00e3o da Ret\u00f3rica","author":"Radam\u00e9s","date":false,"format":false,"excerpt":"\u00c9 surpreendente a Ret\u00f3rica ter surgido pujante h\u00e1 mais de dois mil anos, numa \u00e9poca de parcos recursos de an\u00e1lise, que nem de longe se comparam aos que dispomos hoje. Mais surpreendente ainda \u00e9 a hiberna\u00e7\u00e3o milenar em que a Ret\u00f3rica ingressou ap\u00f3s seu per\u00edodo \u00e1ureo, mesmo sendo objeto de\u2026","rel":"","context":"Em &quot;Para come\u00e7ar&quot;","block_context":{"text":"Para come\u00e7ar","link":"https:\/\/radames.manosso.nom.br\/linguagem\/category\/retorica\/para-comecar\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":52,"url":"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-monografia\/","url_meta":{"origin":45,"position":3},"title":"Ret\u00f3rica da monografia","author":"Radam\u00e9s","date":false,"format":false,"excerpt":"Monografia \u00e9 um discurso dissertativo curto de tema \u00fanico e restrito. Muitos discursos como reda\u00e7\u00e3o escolar, not\u00edcia, reportagem, pronunciamento de ocasi\u00e3o, relat\u00f3rio, palestra, entre outros, se enquadram nessa defini\u00e7\u00e3o bastante gen\u00e9rica. Tal diversidade torna quase imposs\u00edvel estabelecer uma Ret\u00f3rica de monografias. Qualquer tentativa neste sentido ter\u00e1 que se basear no\u2026","rel":"","context":"Em &quot;Ret\u00f3ricas&quot;","block_context":{"text":"Ret\u00f3ricas","link":"https:\/\/radames.manosso.nom.br\/linguagem\/category\/retorica\/retoricas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":47,"url":"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-do-jornalismo\/","url_meta":{"origin":45,"position":4},"title":"Ret\u00f3rica do jornalismo","author":"Radam\u00e9s","date":false,"format":false,"excerpt":"Vamos admitir a exist\u00eancia de alguns princ\u00edpios leg\u00edtimos que norteiam o jornalismo s\u00f3brio. Se s\u00e3o princ\u00edpios ut\u00f3picos ou mesmo de fachada, \u00e9 quest\u00e3o para discuss\u00e3o filos\u00f3fica. O fato \u00e9 que esses princ\u00edpios norteiam toda a Ret\u00f3rica do discurso jornal\u00edstico. Vejamos alguns deles: Objetividade: discurso objetivo \u00e9 aquele que d\u00e1 ao\u2026","rel":"","context":"Em &quot;Ret\u00f3ricas&quot;","block_context":{"text":"Ret\u00f3ricas","link":"https:\/\/radames.manosso.nom.br\/linguagem\/category\/retorica\/retoricas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":49,"url":"https:\/\/radames.manosso.nom.br\/linguagem\/retorica\/retoricas\/retorica-da-influencia\/","url_meta":{"origin":45,"position":5},"title":"Ret\u00f3rica da persuas\u00e3o","author":"Radam\u00e9s","date":false,"format":false,"excerpt":"Por persuas\u00e3o entenda-se convencer, aliciar, mover, incitar \u00e0 a\u00e7\u00e3o.\u00a0 Os meios que importam \u00e0 Ret\u00f3rica para atingir estes fins s\u00e3o a explana\u00e7\u00e3o, a argumenta\u00e7\u00e3o l\u00f3gica e paral\u00f3gica e a persuas\u00e3o pelo discurso. Elementos da ret\u00f3rica persuasiva Alguns conceitos \u00fateis para a compreens\u00e3o da ret\u00f3rica persuasiva: Explana\u00e7\u00e3o: \u00c9 o discurso que\u2026","rel":"","context":"Em &quot;Ret\u00f3ricas&quot;","block_context":{"text":"Ret\u00f3ricas","link":"https:\/\/radames.manosso.nom.br\/linguagem\/category\/retorica\/retoricas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radames.manosso.nom.br\/linguagem\/files\/retorica-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/posts\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":3,"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/posts\/45\/revisions"}],"predecessor-version":[{"id":3996,"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/posts\/45\/revisions\/3996"}],"wp:attachment":[{"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/media?parent=45"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/categories?post=45"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radames.manosso.nom.br\/linguagem\/wp-json\/wp\/v2\/tags?post=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}